{"id":16718,"date":"2024-06-10T16:02:07","date_gmt":"2024-06-10T21:02:07","guid":{"rendered":"https:\/\/5badbfa87a.nxcli.io\/pease\/?post_type=tribe_events&#038;p=16718"},"modified":"2024-06-10T16:02:07","modified_gmt":"2024-06-10T21:02:07","slug":"election-day-no-school-professional-development-teachers","status":"publish","type":"tribe_events","link":"https:\/\/mtcs.org\/pease\/calendar\/election-day-no-school-professional-development-teachers\/","title":{"rendered":"Election Day&#8211;No School&#8211;Professional Development Teachers"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":4,"featured_media":0,"template":"","meta":{"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":""},"tags":[],"tribe_events_cat":[],"class_list":["post-16718","tribe_events","type-tribe_events","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Election Day--No School--Professional Development Teachers &#060; P.E.A.S.E. Academy<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mtcs.org\/pease\/calendar\/election-day-no-school-professional-development-teachers\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Election Day--No School--Professional Development Teachers &#060; P.E.A.S.E. Academy\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mtcs.org\/pease\/calendar\/election-day-no-school-professional-development-teachers\/\" \/>\n<meta property=\"og:site_name\" content=\"P.E.A.S.E. Academy\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/PEASE-Academy-130307271306\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@peaseacademy\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mtcs.org\\\/pease\\\/calendar\\\/election-day-no-school-professional-development-teachers\\\/\",\"url\":\"https:\\\/\\\/mtcs.org\\\/pease\\\/calendar\\\/election-day-no-school-professional-development-teachers\\\/\",\"name\":\"Election Day--No School--Professional Development Teachers &#060; P.E.A.S.E. Academy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mtcs.org\\\/pease\\\/#website\"},\"datePublished\":\"2024-06-10T21:02:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mtcs.org\\\/pease\\\/calendar\\\/election-day-no-school-professional-development-teachers\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mtcs.org\\\/pease\\\/calendar\\\/election-day-no-school-professional-development-teachers\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mtcs.org\\\/pease\\\/calendar\\\/election-day-no-school-professional-development-teachers\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/mtcs.org\\\/pease\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Events\",\"item\":\"https:\\\/\\\/mtcs.org\\\/pease\\\/calendar\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Election Day&#8211;No School&#8211;Professional Development Teachers\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mtcs.org\\\/pease\\\/#website\",\"url\":\"https:\\\/\\\/mtcs.org\\\/pease\\\/\",\"name\":\"P.E.A.S.E. Academy\",\"description\":\"Serving Grades 9-12+ Students in Recovery\",\"publisher\":{\"@id\":\"https:\\\/\\\/mtcs.org\\\/pease\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mtcs.org\\\/pease\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mtcs.org\\\/pease\\\/#organization\",\"name\":\"P.E.A.S.E. Academy\",\"url\":\"https:\\\/\\\/mtcs.org\\\/pease\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/mtcs.org\\\/pease\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mtcs.org\\\/pease\\\/wp-content\\\/uploads\\\/sites\\\/9\\\/2017\\\/09\\\/peaselogo.png\",\"contentUrl\":\"https:\\\/\\\/mtcs.org\\\/pease\\\/wp-content\\\/uploads\\\/sites\\\/9\\\/2017\\\/09\\\/peaselogo.png\",\"width\":205,\"height\":205,\"caption\":\"P.E.A.S.E. Academy\"},\"image\":{\"@id\":\"https:\\\/\\\/mtcs.org\\\/pease\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/PEASE-Academy-130307271306\\\/\",\"https:\\\/\\\/x.com\\\/peaseacademy\",\"https:\\\/\\\/www.instagram.com\\\/pease_academy\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Election Day--No School--Professional Development Teachers &#060; P.E.A.S.E. Academy","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mtcs.org\/pease\/calendar\/election-day-no-school-professional-development-teachers\/","og_locale":"en_US","og_type":"article","og_title":"Election Day--No School--Professional Development Teachers &#060; P.E.A.S.E. Academy","og_url":"https:\/\/mtcs.org\/pease\/calendar\/election-day-no-school-professional-development-teachers\/","og_site_name":"P.E.A.S.E. Academy","article_publisher":"https:\/\/www.facebook.com\/PEASE-Academy-130307271306\/","twitter_card":"summary_large_image","twitter_site":"@peaseacademy","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mtcs.org\/pease\/calendar\/election-day-no-school-professional-development-teachers\/","url":"https:\/\/mtcs.org\/pease\/calendar\/election-day-no-school-professional-development-teachers\/","name":"Election Day--No School--Professional Development Teachers &#060; P.E.A.S.E. Academy","isPartOf":{"@id":"https:\/\/mtcs.org\/pease\/#website"},"datePublished":"2024-06-10T21:02:07+00:00","breadcrumb":{"@id":"https:\/\/mtcs.org\/pease\/calendar\/election-day-no-school-professional-development-teachers\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mtcs.org\/pease\/calendar\/election-day-no-school-professional-development-teachers\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/mtcs.org\/pease\/calendar\/election-day-no-school-professional-development-teachers\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mtcs.org\/pease\/"},{"@type":"ListItem","position":2,"name":"Events","item":"https:\/\/mtcs.org\/pease\/calendar\/"},{"@type":"ListItem","position":3,"name":"Election Day&#8211;No School&#8211;Professional Development Teachers"}]},{"@type":"WebSite","@id":"https:\/\/mtcs.org\/pease\/#website","url":"https:\/\/mtcs.org\/pease\/","name":"P.E.A.S.E. Academy","description":"Serving Grades 9-12+ Students in Recovery","publisher":{"@id":"https:\/\/mtcs.org\/pease\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mtcs.org\/pease\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/mtcs.org\/pease\/#organization","name":"P.E.A.S.E. Academy","url":"https:\/\/mtcs.org\/pease\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/mtcs.org\/pease\/#\/schema\/logo\/image\/","url":"https:\/\/mtcs.org\/pease\/wp-content\/uploads\/sites\/9\/2017\/09\/peaselogo.png","contentUrl":"https:\/\/mtcs.org\/pease\/wp-content\/uploads\/sites\/9\/2017\/09\/peaselogo.png","width":205,"height":205,"caption":"P.E.A.S.E. Academy"},"image":{"@id":"https:\/\/mtcs.org\/pease\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/PEASE-Academy-130307271306\/","https:\/\/x.com\/peaseacademy","https:\/\/www.instagram.com\/pease_academy\/"]}]}},"_links":{"self":[{"href":"https:\/\/mtcs.org\/pease\/wp-json\/wp\/v2\/tribe_events\/16718","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mtcs.org\/pease\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/mtcs.org\/pease\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/mtcs.org\/pease\/wp-json\/wp\/v2\/users\/4"}],"version-history":[{"count":1,"href":"https:\/\/mtcs.org\/pease\/wp-json\/wp\/v2\/tribe_events\/16718\/revisions"}],"predecessor-version":[{"id":16719,"href":"https:\/\/mtcs.org\/pease\/wp-json\/wp\/v2\/tribe_events\/16718\/revisions\/16719"}],"wp:attachment":[{"href":"https:\/\/mtcs.org\/pease\/wp-json\/wp\/v2\/media?parent=16718"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mtcs.org\/pease\/wp-json\/wp\/v2\/tags?post=16718"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/mtcs.org\/pease\/wp-json\/wp\/v2\/tribe_events_cat?post=16718"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}